{"id":8527,"date":"2021-01-19T20:47:43","date_gmt":"2021-01-19T19:47:43","guid":{"rendered":"https:\/\/teens.cittanuova.it\/?p=8527"},"modified":"2026-06-10T17:06:42","modified_gmt":"2026-06-10T15:06:42","slug":"duplo-zero-zero-residuos-zero-desperdicio","status":"publish","type":"post","link":"https:\/\/teens.cittanuova.it\/eo\/home-box-positions\/home_box_3\/duplo-zero-zero-residuos-zero-desperdicio\/","title":{"rendered":"PT | Objetivo #FomeZero"},"content":{"rendered":"\n<p><span class=\"h-glocal\">Frases como \u201cN\u00e3o gosto da comida\u201d ou \u201cJ\u00e1 estou cheio\u201d tornam-se sempre desculpas f\u00e1ceis para n\u00e3o comer os \u00faltimos 20 gr\u00e3ozinhos de arroz.<\/span><\/p>\n<p>Ver tantas vezes o que deixamos no prato a deslizar para dentro daquele saco preto opaco \u00e9 algo que, de certa forma, deveria levar a repensar comportamentos.<\/p>\n\n\n\n<p>A fome mata! Erradicar a fome e problemas de subnutri\u00e7\u00e3o \u00e9 dos maiores desafios que a nossa gera\u00e7\u00e3o enfrenta e pelo qual n\u00f3s, jovens, devemos lutar de modo a contrariar as repercuss\u00f5es que a Fome continua a ter no Mundo. Este problema n\u00e3o adv\u00e9m de n\u00e3o haver comida para todos, mas da sua constante m\u00e1 distribui\u00e7\u00e3o. Para dar resposta a esta problem\u00e1tica, ficou definida, no 2\u00ba Objetivo de Desenvolvimento Sustent\u00e1vel elaborado em 2015 pela ONU, a import\u00e2ncia de erradicar a fome no mundo at\u00e9 2030.<\/p>\n\n\n\n<p>Por exemplo, se uma empresa de \u00f3culos de sol precisa anunciar no Instagram, entre em contato com um influenciador, que pode ganhar centenas a milhares de euros com uma simples selfie usando a moldura. Obviamente, quanto mais seguidores voc\u00ea tem, mais voc\u00ea ganha. Chiara Ferragni, por exemplo, ganha em m\u00e9dia 12 mil euros por postagem. Isso parece muito? Bem, voc\u00ea tem que pensar no lucro que a empresa obt\u00e9m disso. Em 2016, de fato, cerca de 40% das pessoas que compraram um produto o fizeram depois de ver um influenciador usando-o nas redes sociais. Isso significa que as empresas devem investir em estrelas da web para anunciar seus produtos, e as empresas entenderam isso bem.<\/p>\n\n\n\n<p>Sinal da relev\u00e2ncia deste objetivo foi que o Pr\u00e9mio Nobel da Paz 2020 foi atribu\u00eddo ao Programa Alimentar Mundial, que coordena os esfor\u00e7os da ONU nesta \u00e1rea. No entanto, toda a evolu\u00e7\u00e3o alcan\u00e7ada parece ter sido travada pelos contratempos que 2020 nos tem vindo a apresentar. A pandemia colocou em evid\u00eancia diversas fragilidades do mundo atual. O aumento do desemprego, ao longo destes \u00faltimos meses de crise sanit\u00e1ria, fez com que muitas mais pessoas come\u00e7assem a passar por cen\u00e1rios de pobreza e de fome. Por isso, a partir de agora, levar esta luta em frente est\u00e1 tamb\u00e9m nas tuas m\u00e3os! Vamos deixar-te aqui algumas dicas, factos e uma breve entrevista ao Duarte Marques, membro de uma equipa #FomeZero em Portugal. Pelo fim da Fome no Mundo, est\u00e1s preparado?<\/p>\n\n\n\n<p><span class=\"h-glocal\">| EXPERI\u00caNCIA |<\/span><\/p>\n\n\n\n<p class=\"has-text-align-left\"><span class=\"has-inline-color\" style=\"color: #3168ae;\"><strong>Asamanech Asmelash<\/strong> \u00e9 um estudante et\u00edope e gosta de ir \u00e0 escola. \u00c0s vezes era dif\u00edcil concentrar-se nas aulas devido \u00e0 fome. <strong>Este problema afetava tamb\u00e9m v\u00e1rios dos seus colegas, que faltavam muitas vezes \u00e0 escola e outros que at\u00e9 desistiram. <\/strong>Atrav\u00e9s do programa de refei\u00e7\u00f5es escolares associado \u00e0 FomeZero, Asamanech consegue agora concentrar-se e obter melhores resultados. Isto \u00e9 poss\u00edvel com a ajuda da FAO (Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Agricultura e Alimenta\u00e7\u00e3o), que d\u00e1 aos produtores locais sementes e instrumentos. Ensina-os a reduzir a quantidade de perda de alimentos, devido \u00e0 sua m\u00e1 conserva\u00e7\u00e3o, e ajuda igualmente os produtores a venderem a sua produ\u00e7\u00e3o nos mercados, em coordena\u00e7\u00e3o com o programa de alimenta\u00e7\u00e3o escolar. <strong>Asamanech e a sua fam\u00edlia est\u00e3o muito felizes por fazer parte do programa e ele diz que agora v\u00ea \u00abum futuro brilhante \u00e0 sua frente\u00bb!<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juntos somos mais fortes | Um compromisso para um mundo unido <a class=\"g1-link g1-link-more\" href=\"https:\/\/teens.cittanuova.it\/eo\/home-box-positions\/home_box_3\/duplo-zero-zero-residuos-zero-desperdicio\/\">More<\/a><\/p>\n","protected":false},"author":1,"featured_media":9952,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1963,449,2231],"tags":[],"adace-sponsor":[],"wps_subtitle":"Uma proposta para recuperar produtos aliment\u00edcios pr\u00f3ximos do vencimento, para eliminar desperd\u00edcios e vencer a pobreza.","_links":{"self":[{"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/posts\/8527"}],"collection":[{"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/comments?post=8527"}],"version-history":[{"count":39,"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/posts\/8527\/revisions"}],"predecessor-version":[{"id":9959,"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/posts\/8527\/revisions\/9959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/media\/9952"}],"wp:attachment":[{"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/media?parent=8527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/categories?post=8527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/tags?post=8527"},{"taxonomy":"adace-sponsor","embeddable":true,"href":"https:\/\/teens.cittanuova.it\/eo\/wp-json\/wp\/v2\/adace-sponsor?post=8527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}